{"id":1369,"date":"2025-10-17T13:06:06","date_gmt":"2025-10-17T11:06:06","guid":{"rendered":"https:\/\/anywhere.academy\/?post_type=lernwelten&#038;p=1369"},"modified":"2025-12-10T16:21:02","modified_gmt":"2025-12-10T15:21:02","slug":"conference_room","status":"publish","type":"lernwelten","link":"https:\/\/anywhere.academy\/en\/lernwelten\/conference_room\/","title":{"rendered":"Conference Room"},"content":{"rendered":"<div data-is-block=\"jet-engine\/dynamic-image\"><div class=\"jet-listing jet-listing-dynamic-image\" ><a href=\"https:\/\/anywhere.academy\/en\/lernwelten\/conference_room\/\" class=\"jet-listing-dynamic-image__link\"><\/a><\/div><\/div>\n\n\n<p>Nutzer*innen, die den Conference Room betreten, landen zun\u00e4chst in der eher gem\u00fctlich gestalteten Hangout-Zone. Dort k\u00f6nnen sie sich zun\u00e4chst mit der virtuellen Umgebung vertraut machen, ohne direkt mit einer Aufgabe konfrontiert zu werden. Gleichzeitig erm\u00f6glicht das lockere Umfeld einen zwanglosen ersten Kontakt mit den anderen Teilnehmenden der Session. Dadurch soll ein grunds\u00e4tzlich positiver und entspannter Social Space geschaffen werden.<\/p>\n\n\n\n<p>Einfache Interaktionen mit der virtuellen Welt k\u00f6nnen mithilfe der vorhandenen Kaffeemaschine erprobt werden. In sp\u00e4teren Updates wird die Hangout-Zone noch um weitere Funktionen erweitert, um das Erlebnis noch interaktiver zu gestalten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-1024x576.jpg\" alt=\"\" class=\"wp-image-822\" srcset=\"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-1024x576.jpg 1024w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-300x169.jpg 300w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-768x432.jpg 768w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/elementor\/thumbs\/ConferenceCube_inGame_2-r3c72ni7ji6ouvarxstfnu5ione32nafuiuzrlafve.jpg 14w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Sobald die Teilnehmenden sich mit der Umgebung und auch untereinander bekannt gemacht haben, k\u00f6nnen sie den Workspace betreten. Dort finden sie einen gro\u00dfen Konferenztisch mit bis zu 10 Arbeitspl\u00e4tzen, die f\u00fcr die Zusammenarbeit genutzt werden k\u00f6nnen. Dieser Teil des Szenarios ist deutlich neutraler gestaltet, um Ablenkungen zu vermeiden und produktive Arbeit zu f\u00f6rdern. Die St\u00fchle sind benutzbar und k\u00f6nnen so daf\u00fcr genutzt werden, die Nutzung von VR im Sitzen zu erm\u00f6glichen, ohne dabei das Pr\u00e4senzempfinden (etwa durch ungew\u00f6hnliche Haltungen der Avatare) zu st\u00f6ren. Dies kann zur Vermeidung von Motion-Sickness beitragen und daher l\u00e4ngere Aufenthalte in VR zur effektiven Zusammenarbeit erm\u00f6glichen.<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_1-1024x576.jpg\" alt=\"\" class=\"wp-image-821\" srcset=\"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_1-1024x576.jpg 1024w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_1-300x169.jpg 300w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_1-768x432.jpg 768w, https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><br>Die Implementierung einiger Produktivit\u00e4tstools zum gemeinsamen Arbeiten wird in kommenden Updates spannende M\u00f6glichkeiten zur Zusammenarbeit bieten. Geplant sind unter anderem ein geteilter Bildschirm f\u00fcr die Freigabe von Browser-Inhalten, aber auch synchronisierte Zeichentools und mehr.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"template":"","class_list":["post-1369","lernwelten","type-lernwelten","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conference Room - Anywhere Academy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anywhere.academy\/en\/lernwelten\/conference_room\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conference Room - Anywhere Academy\" \/>\n<meta property=\"og:description\" content=\"Nutzer*innen, die den Conference Room betreten, landen zun\u00e4chst in der eher gem\u00fctlich gestalteten Hangout-Zone. Dort k\u00f6nnen sie sich zun\u00e4chst mit der virtuellen Umgebung vertraut machen, ohne direkt mit einer Aufgabe konfrontiert zu werden. Gleichzeitig erm\u00f6glicht das lockere Umfeld einen zwanglosen ersten Kontakt mit den anderen Teilnehmenden der Session. Dadurch soll ein grunds\u00e4tzlich positiver und entspannter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anywhere.academy\/en\/lernwelten\/conference_room\/\" \/>\n<meta property=\"og:site_name\" content=\"Anywhere Academy\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T15:21:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/\",\"url\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/\",\"name\":\"Conference Room - Anywhere Academy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anywhere.academy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anywhere.academy\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ConferenceCube_inGame_2-1024x576.jpg\",\"datePublished\":\"2025-10-17T11:06:06+00:00\",\"dateModified\":\"2025-12-10T15:21:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anywhere.academy\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ConferenceCube_inGame_2-1024x576.jpg\",\"contentUrl\":\"https:\\\/\\\/anywhere.academy\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ConferenceCube_inGame_2-1024x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anywhere.academy\\\/lernwelten\\\/conference_room\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/anywhere.academy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conference Room\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anywhere.academy\\\/#website\",\"url\":\"https:\\\/\\\/anywhere.academy\\\/\",\"name\":\"Anywhere Academy\",\"description\":\"Avatar-Based Teaching and Learning in VR\",\"publisher\":{\"@id\":\"https:\\\/\\\/anywhere.academy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anywhere.academy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anywhere.academy\\\/#organization\",\"name\":\"Anywhere Academy\",\"url\":\"https:\\\/\\\/anywhere.academy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/anywhere.academy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anywhere.academy\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/AA-Logo-And-Name-Horizontal-Colour.svg\",\"contentUrl\":\"https:\\\/\\\/anywhere.academy\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/AA-Logo-And-Name-Horizontal-Colour.svg\",\"width\":6051,\"height\":1907,\"caption\":\"Anywhere Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/anywhere.academy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/hydrology_rwth\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conference Room - Anywhere Academy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anywhere.academy\/en\/lernwelten\/conference_room\/","og_locale":"en_GB","og_type":"article","og_title":"Conference Room - Anywhere Academy","og_description":"Nutzer*innen, die den Conference Room betreten, landen zun\u00e4chst in der eher gem\u00fctlich gestalteten Hangout-Zone. Dort k\u00f6nnen sie sich zun\u00e4chst mit der virtuellen Umgebung vertraut machen, ohne direkt mit einer Aufgabe konfrontiert zu werden. Gleichzeitig erm\u00f6glicht das lockere Umfeld einen zwanglosen ersten Kontakt mit den anderen Teilnehmenden der Session. Dadurch soll ein grunds\u00e4tzlich positiver und entspannter [&hellip;]","og_url":"https:\/\/anywhere.academy\/en\/lernwelten\/conference_room\/","og_site_name":"Anywhere Academy","article_modified_time":"2025-12-10T15:21:02+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/","url":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/","name":"Conference Room - Anywhere Academy","isPartOf":{"@id":"https:\/\/anywhere.academy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/#primaryimage"},"image":{"@id":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/#primaryimage"},"thumbnailUrl":"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-1024x576.jpg","datePublished":"2025-10-17T11:06:06+00:00","dateModified":"2025-12-10T15:21:02+00:00","breadcrumb":{"@id":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anywhere.academy\/lernwelten\/conference_room\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/#primaryimage","url":"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-1024x576.jpg","contentUrl":"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/03\/ConferenceCube_inGame_2-1024x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/anywhere.academy\/lernwelten\/conference_room\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/anywhere.academy\/"},{"@type":"ListItem","position":2,"name":"Conference Room"}]},{"@type":"WebSite","@id":"https:\/\/anywhere.academy\/#website","url":"https:\/\/anywhere.academy\/","name":"Anywhere Academy","description":"Avatar-Based Teaching and Learning in VR","publisher":{"@id":"https:\/\/anywhere.academy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anywhere.academy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/anywhere.academy\/#organization","name":"Anywhere Academy","url":"https:\/\/anywhere.academy\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/anywhere.academy\/#\/schema\/logo\/image\/","url":"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/02\/AA-Logo-And-Name-Horizontal-Colour.svg","contentUrl":"https:\/\/anywhere.academy\/wp-content\/uploads\/2025\/02\/AA-Logo-And-Name-Horizontal-Colour.svg","width":6051,"height":1907,"caption":"Anywhere Academy"},"image":{"@id":"https:\/\/anywhere.academy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/hydrology_rwth\/"]}]}},"_links":{"self":[{"href":"https:\/\/anywhere.academy\/en\/wp-json\/wp\/v2\/lernwelten\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anywhere.academy\/en\/wp-json\/wp\/v2\/lernwelten"}],"about":[{"href":"https:\/\/anywhere.academy\/en\/wp-json\/wp\/v2\/types\/lernwelten"}],"wp:attachment":[{"href":"https:\/\/anywhere.academy\/en\/wp-json\/wp\/v2\/media?parent=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}